{"id":782,"date":"2026-05-07T13:14:12","date_gmt":"2026-05-07T11:14:12","guid":{"rendered":"https:\/\/ecolestjbosco.fr\/?p=782"},"modified":"2026-05-07T13:14:12","modified_gmt":"2026-05-07T11:14:12","slug":"cirque-avec-locspac","status":"publish","type":"post","link":"https:\/\/ecolestjbosco.fr\/index.php\/2026\/05\/07\/cirque-avec-locspac\/","title":{"rendered":"Cirque avec l&#8217;Ocspac"},"content":{"rendered":"\n<p>En cette derni\u00e8re p\u00e9riode de l&#8217;ann\u00e9e, les \u00e9l\u00e8ves de maternelle ont commenc\u00e9  des activit\u00e9s de cirque avec Clovis, l&#8217;animateur de l&#8217;Ocspac. Au programme, jonglage, \u00e9quilibre&#8230; De vrais petits artistes!<\/p>\n\n\n\n<figure class=\"wp-block-image size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"393\" height=\"510\" src=\"https:\/\/ecolestjbosco.fr\/wp-content\/uploads\/2026\/05\/image.png\" alt=\"\" class=\"wp-image-783\" srcset=\"https:\/\/ecolestjbosco.fr\/wp-content\/uploads\/2026\/05\/image.png 393w, https:\/\/ecolestjbosco.fr\/wp-content\/uploads\/2026\/05\/image-231x300.png 231w\" sizes=\"(max-width: 393px) 100vw, 393px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"390\" height=\"520\" src=\"https:\/\/ecolestjbosco.fr\/wp-content\/uploads\/2026\/05\/image-1.png\" alt=\"\" class=\"wp-image-784\" srcset=\"https:\/\/ecolestjbosco.fr\/wp-content\/uploads\/2026\/05\/image-1.png 390w, https:\/\/ecolestjbosco.fr\/wp-content\/uploads\/2026\/05\/image-1-225x300.png 225w\" sizes=\"(max-width: 390px) 100vw, 390px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"687\" height=\"513\" src=\"https:\/\/ecolestjbosco.fr\/wp-content\/uploads\/2026\/05\/image-2.png\" alt=\"\" class=\"wp-image-785\" srcset=\"https:\/\/ecolestjbosco.fr\/wp-content\/uploads\/2026\/05\/image-2.png 687w, https:\/\/ecolestjbosco.fr\/wp-content\/uploads\/2026\/05\/image-2-300x224.png 300w\" sizes=\"(max-width: 687px) 100vw, 687px\" \/><\/figure>\n","protected":false},"excerpt":{"rendered":"<p>En cette derni\u00e8re p\u00e9riode de l&#8217;ann\u00e9e, les \u00e9l\u00e8ves de maternelle ont commenc\u00e9 des activit\u00e9s de cirque avec Clovis, l&#8217;animateur de l&#8217;Ocspac. Au programme, jonglage, \u00e9quilibre&#8230; De vrais petits artistes!<\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[3],"tags":[],"class_list":["post-782","post","type-post","status-publish","format-standard","hentry","category-la-vie-decole"],"_links":{"self":[{"href":"https:\/\/ecolestjbosco.fr\/index.php\/wp-json\/wp\/v2\/posts\/782"}],"collection":[{"href":"https:\/\/ecolestjbosco.fr\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/ecolestjbosco.fr\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/ecolestjbosco.fr\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/ecolestjbosco.fr\/index.php\/wp-json\/wp\/v2\/comments?post=782"}],"version-history":[{"count":1,"href":"https:\/\/ecolestjbosco.fr\/index.php\/wp-json\/wp\/v2\/posts\/782\/revisions"}],"predecessor-version":[{"id":786,"href":"https:\/\/ecolestjbosco.fr\/index.php\/wp-json\/wp\/v2\/posts\/782\/revisions\/786"}],"wp:attachment":[{"href":"https:\/\/ecolestjbosco.fr\/index.php\/wp-json\/wp\/v2\/media?parent=782"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/ecolestjbosco.fr\/index.php\/wp-json\/wp\/v2\/categories?post=782"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/ecolestjbosco.fr\/index.php\/wp-json\/wp\/v2\/tags?post=782"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}