{"id":223,"date":"2025-02-05T21:43:40","date_gmt":"2025-02-05T20:43:40","guid":{"rendered":"https:\/\/ecolestjbosco.fr\/?p=223"},"modified":"2025-02-05T21:48:31","modified_gmt":"2025-02-05T20:48:31","slug":"2025-01-journee-bricolage","status":"publish","type":"post","link":"https:\/\/ecolestjbosco.fr\/index.php\/2025\/02\/05\/2025-01-journee-bricolage\/","title":{"rendered":"2025-01 Journ\u00e9e Bricolage"},"content":{"rendered":"\n<p>Samedi 18 janvier a eu lieu la seconde journ\u00e9e bricolage. De nombreux parents ont r\u00e9pondu pr\u00e9sents.<\/p>\n\n\n\n<p>Merci aux familles pr\u00e9sentes. Nous vous esp\u00e9rons encore plus nombreux la prochaine fois.<\/p>\n\n\n\n<figure class=\"wp-block-gallery has-nested-images columns-default is-cropped wp-block-gallery-1 is-layout-flex wp-block-gallery-is-layout-flex\">\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"564\" height=\"752\" data-id=\"240\" src=\"https:\/\/ecolestjbosco.fr\/wp-content\/uploads\/2025\/02\/jb4-1.jpg\" alt=\"\" class=\"wp-image-240\" srcset=\"https:\/\/ecolestjbosco.fr\/wp-content\/uploads\/2025\/02\/jb4-1.jpg 564w, https:\/\/ecolestjbosco.fr\/wp-content\/uploads\/2025\/02\/jb4-1-225x300.jpg 225w\" sizes=\"(max-width: 564px) 100vw, 564px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"826\" height=\"619\" data-id=\"241\" src=\"https:\/\/ecolestjbosco.fr\/wp-content\/uploads\/2025\/02\/jb3-3.jpg\" alt=\"\" class=\"wp-image-241\" srcset=\"https:\/\/ecolestjbosco.fr\/wp-content\/uploads\/2025\/02\/jb3-3.jpg 826w, https:\/\/ecolestjbosco.fr\/wp-content\/uploads\/2025\/02\/jb3-3-300x225.jpg 300w, https:\/\/ecolestjbosco.fr\/wp-content\/uploads\/2025\/02\/jb3-3-768x576.jpg 768w\" sizes=\"(max-width: 767px) 89vw, (max-width: 1000px) 54vw, (max-width: 1071px) 543px, 580px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"542\" height=\"722\" data-id=\"243\" src=\"https:\/\/ecolestjbosco.fr\/wp-content\/uploads\/2025\/02\/jb2-4.jpg\" alt=\"\" class=\"wp-image-243\" srcset=\"https:\/\/ecolestjbosco.fr\/wp-content\/uploads\/2025\/02\/jb2-4.jpg 542w, https:\/\/ecolestjbosco.fr\/wp-content\/uploads\/2025\/02\/jb2-4-225x300.jpg 225w\" sizes=\"(max-width: 542px) 100vw, 542px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"575\" height=\"767\" data-id=\"242\" src=\"https:\/\/ecolestjbosco.fr\/wp-content\/uploads\/2025\/02\/jb1-4.jpg\" alt=\"\" class=\"wp-image-242\" srcset=\"https:\/\/ecolestjbosco.fr\/wp-content\/uploads\/2025\/02\/jb1-4.jpg 575w, https:\/\/ecolestjbosco.fr\/wp-content\/uploads\/2025\/02\/jb1-4-225x300.jpg 225w\" sizes=\"(max-width: 575px) 100vw, 575px\" \/><\/figure>\n<\/figure>\n","protected":false},"excerpt":{"rendered":"<p>Samedi 18 janvier a eu lieu la seconde journ\u00e9e bricolage. De nombreux parents ont r\u00e9pondu pr\u00e9sents. Merci aux familles pr\u00e9sentes. Nous vous esp\u00e9rons encore plus nombreux la prochaine fois.<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[3],"tags":[],"class_list":["post-223","post","type-post","status-publish","format-standard","hentry","category-la-vie-decole"],"_links":{"self":[{"href":"https:\/\/ecolestjbosco.fr\/index.php\/wp-json\/wp\/v2\/posts\/223"}],"collection":[{"href":"https:\/\/ecolestjbosco.fr\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/ecolestjbosco.fr\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/ecolestjbosco.fr\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/ecolestjbosco.fr\/index.php\/wp-json\/wp\/v2\/comments?post=223"}],"version-history":[{"count":2,"href":"https:\/\/ecolestjbosco.fr\/index.php\/wp-json\/wp\/v2\/posts\/223\/revisions"}],"predecessor-version":[{"id":244,"href":"https:\/\/ecolestjbosco.fr\/index.php\/wp-json\/wp\/v2\/posts\/223\/revisions\/244"}],"wp:attachment":[{"href":"https:\/\/ecolestjbosco.fr\/index.php\/wp-json\/wp\/v2\/media?parent=223"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/ecolestjbosco.fr\/index.php\/wp-json\/wp\/v2\/categories?post=223"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/ecolestjbosco.fr\/index.php\/wp-json\/wp\/v2\/tags?post=223"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}